{"id":2270,"date":"2018-06-12T07:42:52","date_gmt":"2018-06-12T12:42:52","guid":{"rendered":"http:\/\/ministerioaguadevida.net\/jovenes\/?p=2270"},"modified":"2018-06-12T07:42:52","modified_gmt":"2018-06-12T12:42:52","slug":"nuestro-refugio","status":"publish","type":"post","link":"http:\/\/ministerioaguadevida.net\/jovenes\/2018\/06\/12\/nuestro-refugio\/","title":{"rendered":"Nuestro Refugio"},"content":{"rendered":"<p>Ninguna arma forjada contra ti prosperar\u00e1, y condenar\u00e1s toda lengua que se levante contra ti en juicio. \u00c9sta es la herencia de los siervos de Jehov\u00e1, y su salvaci\u00f3n de m\u00ed vendr\u00e1, dijo Jehov\u00e1.<br \/>\nIsa\u00edas 54:17 RVR1960<\/p>\n<p>Buenos d\u00edas <\/p>\n<p>Ser hijos de Dios no nos exime de pasar por dificultades, antes puede que nos traiga m\u00e1s, pues al momento de empezar a servir a Dios nos hacemos de un enemigo el cu\u00e1l est\u00e1 interesado en que no avancemos y tratara por todos los medios de estorbarnos, sin embargo en medio de todo esto nosotros podremos estar tranquilos en que los planes del enemigo ni de ninguna otra persona en contra de nosotros prosperar\u00e1, pues Dios mismo nos defiende. <\/p>\n<p>Por lo cual no debemos asustarnos ni detenernos de hacer las cosas que Dios nos mando a hacer, por el contrario esto lo que debe hacer es animarnos a dar la pelea y a esforzarnos cada vez m\u00e1s, sabiendo que Dios es quien va delante de nosotros, como dice la palabra el reino de los cielos lo arrebatan los valientes y Dios requiere valent\u00eda de parte de todos nosotros, requiere que nos levantemos y alumbremos a nuestra generaci\u00f3n y que lo hagamos a\u00fan en medio de las dificultades que esto nos puede traer, adem\u00e1s si sabemos que Dios nos ha entregado la victoria entonces \u00bfque nos detiene? No dejemos que el enemigo nos tome ventaja y mucho menos tengamos miedo de \u00e9l, pues es un enemigo derrotado.<\/p>\n<p>Este vers\u00edculo aplica para nuestros planes, sue\u00f1os y dem\u00e1s, pero principalmente aplica para la obra que Dios nos ha encargado y hoy mi invitaci\u00f3n es a que no permitas que tu ministerio se estanque, todos tenemos un llamado y nadie va a hacer esa tarea por nosotros, depende de nosotros mismos, examinemos a diario y si sientes que nos ha hecho suficiente para la obra de Dios entonces ponte manos a la obra o si sientes que vas por buen camino entonces mantente as\u00ed y sigue dando lo mejor.<br \/>\nLa buena noticia es que aunque traten de detenerte ning\u00fan arma prosperar\u00e1. <\/p>\n<p>Dios los bendiga bendiciones<\/p>\n<p><strong>Juan David Jara Rosas &#8211; Ministerio Juvenil Agua de Vida<\/strong><\/p>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t.huge-it-share-buttons {\n\t\t\t\t\t\t\t\tborder:0px solid #0FB5D6;\n\t\t\t\t\t\t\t\tborder-radius:5px;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t#huge-it-share-buttons-top {margin-bottom:0px;}\n\t\t\t\t\t\t\t#huge-it-share-buttons-bottom {margin-top:0px;}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons h3 {\n\t\t\t\t\t\t\t\tfont-size:25px ;\n\t\t\t\t\t\t\t\tfont-family:Arial,Helvetica Neue,Helvetica,sans-serif;\n\t\t\t\t\t\t\t\tcolor:#666666;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tdisplay:block;\t\t\t\t\t\t\t\tline-height:25px ;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul {\t\n\t\t\t\t\t\t\t\t float:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li {\n\t\t\t\t\t\t\t\tmargin-left:3px !important;\n\t\t\t\t\t\t\t\tmargin-right:3px !important;\n\t\t\t\t\t\t\t\tpadding:0px;\n\t\t\t\t\t\t\t\tborder:0px ridge #E6354C;\n\t\t\t\t\t\t\t\tborder-radius:11px;\n\t\t\t\t\t\t\t\tbackground-color:#14CC9B;\n\t\t\t\t\t\t\t\twidth:auto !important;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li #backforunical2270 {\n\t\t\t\t\t\t\t\tbackground-image:url('http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/buttons.20.png');\n\t\t\t\t\t\t\t\twidth:20px;\n\t\t\t\t\t\t\t\theight:20px;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"huge-it-share-buttons-top\" class=\"huge-it-share-buttons nobackground\">\n\t\t\t\t\t\t\t<h3>Share This:<\/h3>\n\t\t\t\t\t\t\t<ul class=\"huge-it-share-buttons-list\">\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -0px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&text=Nuestro Refugio\"  onclick=\"javascript:void window.open('https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&text=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -20px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -40px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -60px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/www.linkedin.com\/shareArticle?title=Nuestro Refugio&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('https:\/\/www.linkedin.com\/shareArticle?title=Nuestro Refugio&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -80px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&name=Nuestro Refugio\"  onclick=\"javascript:void window.open('https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&name=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -100px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -120px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -140px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -160px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -180px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -200px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -220px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -240px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\"  onclick=\"javascript:void window.open('http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -260px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -280px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&appkey=&title=Nuestro Refugio&pic=&ralateUid=&\"  onclick=\"javascript:void window.open('http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&appkey=&title=Nuestro Refugio&pic=&ralateUid=&','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -300px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -320px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2270\" href=\"http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio\"  onclick=\"javascript:void window.open('http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270&title=Nuestro Refugio','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -340px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\n\t\n\n\t","protected":false},"excerpt":{"rendered":"<p>Ninguna arma forjada contra ti prosperar\u00e1, y condenar\u00e1s toda lengua que se levante contra ti en juicio. \u00c9sta es la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270"}],"collection":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/comments?post=2270"}],"version-history":[{"count":1,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\/revisions"}],"predecessor-version":[{"id":2271,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2270\/revisions\/2271"}],"wp:attachment":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/media?parent=2270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/categories?post=2270"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/tags?post=2270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}