{"id":2346,"date":"2018-08-21T10:44:45","date_gmt":"2018-08-21T15:44:45","guid":{"rendered":"http:\/\/ministerioaguadevida.net\/jovenes\/?p=2346"},"modified":"2018-08-21T10:44:45","modified_gmt":"2018-08-21T15:44:45","slug":"el-placer-de-vivir-con-dios","status":"publish","type":"post","link":"http:\/\/ministerioaguadevida.net\/jovenes\/2018\/08\/21\/el-placer-de-vivir-con-dios\/","title":{"rendered":"El placer de vivir con Dios"},"content":{"rendered":"<p>Me mostrar\u00e1s el camino de la vida, me conceder\u00e1s la alegr\u00eda de tu presencia y el placer de vivir contigo para siempre.<br \/>\nSalmos 16:11 NTV<\/p>\n<p>Buenos d\u00edas <\/p>\n<p>el mayor placer que podemos experimentar como hijos de Dios es el poder estar en su presencia continuamente, este es un privilegio que tenemos gracias al sacrificio de Jes\u00fas, sin embargo el mundo, el enemigo y nuestros propios deseos continuamente est\u00e1n buscando distraernos y ocuparnos en otras cosas para privarnos de su compa\u00f1\u00eda. Pero nosotros no debemos dejar que esto suceda as\u00ed, sino que d\u00eda tras d\u00eda debemos darnos la oportunidad de disfrutar de la hermosa compa\u00f1\u00eda del Esp\u00edritu Santo, el salmista la conoc\u00eda y muchos otros de los personajes que encontramos en la biblia tambi\u00e9n la conocieron y es por esto que todos ellos estuvieron dispuestos a ir hasta las \u00faltimas consecuencias por amor a Dios, porque su relaci\u00f3n hab\u00eda trascendido y ya no estaba m\u00e1s en la superficie, d\u00eda tras d\u00eda ellos buscaron la esencia de Dios y el resultado de su b\u00fasqueda fue el encontrarse con un tesoro incomparable,hoy mi invitaci\u00f3n es a que nosotros tambi\u00e9n busquemos ese tesoro todos los d\u00edas pues cada d\u00eda encontraremos algo nuevo y fresco en la presencia de Dios. Estar all\u00ed en ese lugar trae alegr\u00eda a nuestro coraz\u00f3n y tambi\u00e9n nos muestra el sentido de vivir, pues realmente no vale la pena vivir alejados de \u00c9l, pero esto es algo que debemos experimentar personalmente, de la misma manera que lo hizo el salmista, mi deseo es que cada uno de nosotros podamos encontrar ese placer de vivir con Dios y podamos disfrutar de su compa\u00f1\u00eda para siempre. <\/p>\n<p>Dios los bendiga feliz d\u00eda<\/p>\n<p><strong>Juan David Jara Rosas &#8211; Ministerio Juvenil Agua de Vida<\/strong><\/p>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t.huge-it-share-buttons {\n\t\t\t\t\t\t\t\tborder:0px solid #0FB5D6;\n\t\t\t\t\t\t\t\tborder-radius:5px;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t#huge-it-share-buttons-top {margin-bottom:0px;}\n\t\t\t\t\t\t\t#huge-it-share-buttons-bottom {margin-top:0px;}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons h3 {\n\t\t\t\t\t\t\t\tfont-size:25px ;\n\t\t\t\t\t\t\t\tfont-family:Arial,Helvetica Neue,Helvetica,sans-serif;\n\t\t\t\t\t\t\t\tcolor:#666666;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tdisplay:block;\t\t\t\t\t\t\t\tline-height:25px ;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul {\t\n\t\t\t\t\t\t\t\t float:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li {\n\t\t\t\t\t\t\t\tmargin-left:3px !important;\n\t\t\t\t\t\t\t\tmargin-right:3px !important;\n\t\t\t\t\t\t\t\tpadding:0px;\n\t\t\t\t\t\t\t\tborder:0px ridge #E6354C;\n\t\t\t\t\t\t\t\tborder-radius:11px;\n\t\t\t\t\t\t\t\tbackground-color:#14CC9B;\n\t\t\t\t\t\t\t\twidth:auto !important;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li #backforunical2346 {\n\t\t\t\t\t\t\t\tbackground-image:url('http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/buttons.20.png');\n\t\t\t\t\t\t\t\twidth:20px;\n\t\t\t\t\t\t\t\theight:20px;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"huge-it-share-buttons-top\" class=\"huge-it-share-buttons nobackground\">\n\t\t\t\t\t\t\t<h3>Share This:<\/h3>\n\t\t\t\t\t\t\t<ul class=\"huge-it-share-buttons-list\">\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -0px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&text=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&text=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -20px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -40px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -60px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/www.linkedin.com\/shareArticle?title=El placer de vivir con Dios&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('https:\/\/www.linkedin.com\/shareArticle?title=El placer de vivir con Dios&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -80px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&name=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&name=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -100px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -120px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -140px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -160px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -180px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -200px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -220px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -240px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\"  onclick=\"javascript:void window.open('http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -260px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -280px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&appkey=&title=El placer de vivir con Dios&pic=&ralateUid=&\"  onclick=\"javascript:void window.open('http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&appkey=&title=El placer de vivir con Dios&pic=&ralateUid=&','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -300px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -320px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2346\" href=\"http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios\"  onclick=\"javascript:void window.open('http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346&title=El placer de vivir con Dios','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -340px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\n\t\n\n\t","protected":false},"excerpt":{"rendered":"<p>Me mostrar\u00e1s el camino de la vida, me conceder\u00e1s la alegr\u00eda de tu presencia y el placer de vivir contigo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346"}],"collection":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/comments?post=2346"}],"version-history":[{"count":1,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\/revisions"}],"predecessor-version":[{"id":2347,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2346\/revisions\/2347"}],"wp:attachment":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/media?parent=2346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/categories?post=2346"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/tags?post=2346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}