{"id":2376,"date":"2018-09-07T08:40:53","date_gmt":"2018-09-07T13:40:53","guid":{"rendered":"http:\/\/ministerioaguadevida.net\/jovenes\/?p=2376"},"modified":"2018-09-07T08:40:53","modified_gmt":"2018-09-07T13:40:53","slug":"el-sueno-de-dios-para-ti","status":"publish","type":"post","link":"http:\/\/ministerioaguadevida.net\/jovenes\/2018\/09\/07\/el-sueno-de-dios-para-ti\/","title":{"rendered":"El sue\u00f1o de Dios para ti"},"content":{"rendered":"<p>Santa Biblia Reina Valera 1960 &#8211; Proverbios 16<br \/>\n9 El coraz\u00f3n del hombre piensa su camino;<br \/>\nMas Jehov\u00e1 endereza sus pasos.<\/p>\n<p>Es normal y adem\u00e1s muy bueno que cada uno de nosotros so\u00f1emos lo que queremos para nuestra vida, lo normal del ser humano es ilusionarse y planear sus pr\u00f3ximos a\u00f1os.<br \/>\nSin embargo en m\u00faltiples ocasiones caemos en la trampa de no poner a Dios en primer momento y adem\u00e1s lo hacemos participe ya cuando establecemos nuestra vida futura en nuestros pensamientos.<\/p>\n<p>No obstante el amor de Dios es tan maravilloso que \u00c9l siempre est\u00e1 ah\u00ed, gui\u00e1ndonos, buscando enderezar nuestros pasos.<\/p>\n<p>Santa Biblia Reina Valera 1960 &#8211; Mateo 26<br \/>\n39 Yendo un poco adelante, se postr\u00f3 sobre su rostro, orando y diciendo: Padre m\u00edo, si es posible, pase de m\u00ed esta copa; pero no sea como yo quiero, sino como t\u00fa.<\/p>\n<p>Como vemos en el vers\u00edculo anterior Jes\u00fas tambi\u00e9n puso pensar en otros planes para su vidas pero antes oro y como ya sabemos Dios ten\u00eda unos planes maravilloso para la vida de Jes\u00fas. <\/p>\n<p>As\u00ed que en esta ma\u00f1ana yo te invito a que pongas tu vida en las manos de Dios, claro que podemos so\u00f1ar, pero debemos ir en sinton\u00eda con nuestro Padre que siempre querr\u00e1 lo mejor para ti y para mi.<\/p>\n<p><strong>Leidy Moreno &#8211; Ministerio Juvenil Agua de Vida<\/strong><\/p>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t.huge-it-share-buttons {\n\t\t\t\t\t\t\t\tborder:0px solid #0FB5D6;\n\t\t\t\t\t\t\t\tborder-radius:5px;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t#huge-it-share-buttons-top {margin-bottom:0px;}\n\t\t\t\t\t\t\t#huge-it-share-buttons-bottom {margin-top:0px;}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons h3 {\n\t\t\t\t\t\t\t\tfont-size:25px ;\n\t\t\t\t\t\t\t\tfont-family:Arial,Helvetica Neue,Helvetica,sans-serif;\n\t\t\t\t\t\t\t\tcolor:#666666;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tdisplay:block;\t\t\t\t\t\t\t\tline-height:25px ;\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t text-align:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul {\t\n\t\t\t\t\t\t\t\t float:left; \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li {\n\t\t\t\t\t\t\t\tmargin-left:3px !important;\n\t\t\t\t\t\t\t\tmargin-right:3px !important;\n\t\t\t\t\t\t\t\tpadding:0px;\n\t\t\t\t\t\t\t\tborder:0px ridge #E6354C;\n\t\t\t\t\t\t\t\tborder-radius:11px;\n\t\t\t\t\t\t\t\tbackground-color:#14CC9B;\n\t\t\t\t\t\t\t\twidth:auto !important;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t.huge-it-share-buttons ul li #backforunical2376 {\n\t\t\t\t\t\t\t\tbackground-image:url('http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/buttons.20.png');\n\t\t\t\t\t\t\t\twidth:20px;\n\t\t\t\t\t\t\t\theight:20px;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"huge-it-share-buttons-top\" class=\"huge-it-share-buttons nobackground\">\n\t\t\t\t\t\t\t<h3>Share This:<\/h3>\n\t\t\t\t\t\t\t<ul class=\"huge-it-share-buttons-list\">\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('https:\/\/www.facebook.com\/sharer\/sharer.php?m2w&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -0px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&text=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('https:\/\/twitter.com\/share?status=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&text=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -20px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/www.pinterest.com\/pin\/create\/button\/?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&media=http:\/\/ministerioaguadevida.net\/jovenes\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -40px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\" nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('https:\/\/plus.google.com\/share?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -60px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/www.linkedin.com\/shareArticle?title=El sue\u00f1o de Dios para ti&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('https:\/\/www.linkedin.com\/shareArticle?title=El sue\u00f1o de Dios para ti&mini=true&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -80px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&name=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('https:\/\/www.tumblr.com\/share\/link?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&name=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -100px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/digg.com\/submit?phase=2&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -120px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/www.stumbleupon.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -140px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('https:\/\/myspace.com\/post?l=3&u=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -160px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/vk.com\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -180px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/www.reddit.com\/submit?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -200px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('http:\/\/www.bebo.com\/c\/share?Url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -220px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('https:\/\/delicious.com\/save?v=5&noui&jump=close&url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -240px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\"  onclick=\"javascript:void window.open('http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -260px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -280px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&appkey=&title=El sue\u00f1o de Dios para ti&pic=&ralateUid=&\"  onclick=\"javascript:void window.open('http:\/\/service.weibo.com\/share\/share.php?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&appkey=&title=El sue\u00f1o de Dios para ti&pic=&ralateUid=&','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -300px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/widget.renren.com\/dialog\/share?resourceUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&srcUrl=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -320px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical2376\" href=\"http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti\"  onclick=\"javascript:void window.open('http:\/\/n4g.com\/tips?url=http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376&title=El sue\u00f1o de Dios para ti','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -340px -80px \"><\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\n\t\n\n\t","protected":false},"excerpt":{"rendered":"<p>Santa Biblia Reina Valera 1960 &#8211; Proverbios 16 9 El coraz\u00f3n del hombre piensa su camino; Mas Jehov\u00e1 endereza sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376"}],"collection":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/comments?post=2376"}],"version-history":[{"count":1,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\/revisions"}],"predecessor-version":[{"id":2377,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/posts\/2376\/revisions\/2377"}],"wp:attachment":[{"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/media?parent=2376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/categories?post=2376"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ministerioaguadevida.net\/jovenes\/wp-json\/wp\/v2\/tags?post=2376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}